{"id":235914,"date":"2013-08-06T20:13:19","date_gmt":"2013-08-06T19:13:19","guid":{"rendered":"https:\/\/www.lageria.com\/classic-shop\/"},"modified":"2026-04-20T07:36:36","modified_gmt":"2026-04-20T06:36:36","slug":"classic-shop","status":"publish","type":"page","link":"https:\/\/dev.lageria.com\/fr\/","title":{"rendered":"Inicio"},"content":{"rendered":"<div class=\"slider-wrapper relative\" id=\"slider-1474928166\" >\n    <div class=\"slider slider-nav-circle slider-nav-large slider-nav-light slider-style-normal\"\n        data-flickity-options='{\n            \"cellAlign\": \"center\",\n            \"imagesLoaded\": true,\n            \"lazyLoad\": 1,\n            \"freeScroll\": false,\n            \"wrapAround\": true,\n            \"autoPlay\": 6000,\n            \"pauseAutoPlayOnHover\" : true,\n            \"prevNextButtons\": true,\n            \"contain\" : true,\n            \"adaptiveHeight\" : true,\n            \"dragThreshold\" : 10,\n            \"percentPosition\": true,\n            \"pageDots\": true,\n            \"rightToLeft\": false,\n            \"draggable\": true,\n            \"selectedAttraction\": 0.1,\n            \"parallax\" : 0,\n            \"friction\": 0.6        }'\n        >\n        \n\n  <div class=\"banner has-hover\" id=\"banner-1120452760\">\n          <div class=\"banner-inner fill\">\n        <div class=\"banner-bg fill\" >\n            <img loading=\"lazy\" decoding=\"async\" width=\"1920\" height=\"1282\" src=\"https:\/\/dev.lageria.com\/wp-content\/uploads\/2025\/10\/IMG_0108-1.jpg\" class=\"bg attachment-original size-original\" alt=\"\" \/>                        <div class=\"overlay\"><\/div>            \n                    <\/div>\n\t\t\n        <div class=\"banner-layers container\">\n            <div class=\"fill banner-link\"><\/div>            \n   <div id=\"text-box-850628050\" class=\"text-box banner-layer x50 md-x50 lg-x50 y50 md-y50 lg-y50 res-text\">\n                     <div data-animate=\"flipInY\">           <div class=\"text-box-content text dark\">\n              \n              <div class=\"text-inner text-center\">\n                  \n<h3 class=\"alt-font\">Les saveurs du volcan dans chaque verre<\/h3>\n<div class=\"is-divider divider clearfix\" style=\"margin-top:3px;margin-bottom:3px;\"><\/div>\n<h1 class=\"h-large uppercase\"><span style=\"font-size: 160%;\"><strong>malvas\u00eda<\/strong><\/span><\/h1>\n<h1 class=\"uppercase\"><span style=\"font-size: 100%;\">lanzarote d.o<br \/><\/span><\/h1>\n<div class=\"is-divider divider clearfix\" ><\/div>\n<a href=\"https:\/\/dev.lageria.com\/en\/shop\/\" class=\"button primary\" >\n\t\t<span>boutique en ligne<\/span>\n\t<\/a>\n\n<a href=\"https:\/\/dev.lageria.com\/fr\/visitas-guiadas\/\" class=\"button alert\" >\n\t\t<span>visite guid\u00e9e<\/span>\n\t<\/a>\n\n<a href=\"https:\/\/dev.lageria.com\/calendario\/\" class=\"button success\" >\n\t\t<span>d\u00e9gustations<\/span>\n\t<\/a>\n\n              <\/div>\n           <\/div>\n       <\/div>                     \n<style>\n#text-box-850628050 {\n  width: 100%;\n}\n#text-box-850628050 .text-box-content {\n  font-size: 100%;\n}\n@media (min-width:550px) {\n  #text-box-850628050 {\n    width: 70%;\n  }\n}\n<\/style>\n    <\/div>\n \n        <\/div>\n      <\/div>\n\n            \n<style>\n#banner-1120452760 {\n  padding-top: 700px;\n}\n#banner-1120452760 .overlay {\n  background-color: rgba(0,0,0,.5);\n}\n#banner-1120452760 .banner-bg img {\n  object-position: 55% 96%;\n}\n<\/style>\n  <\/div>\n\n\n\n  <div class=\"banner has-hover has-video\" id=\"banner-1784447019\">\n          <div class=\"banner-inner fill\">\n        <div class=\"banner-bg fill\" >\n                        \t<div class=\"video-overlay no-click fill hide-for-medium\"><\/div>\n\t<video class=\"video-bg fill hide-for-medium\" preload playsinline autoplay muted loop>\n\t\t<source src=\"https:\/\/dev.lageria.com\/wp-content\/uploads\/2024\/09\/1926425-Dating-Relationship-1920x1080-1.mp4\" type=\"video\/mp4\">\t<\/video>\n            <div class=\"overlay\"><\/div>            \n                    <\/div>\n\t\t\n        <div class=\"banner-layers container\">\n            <div class=\"fill banner-link\"><\/div>            \n   <div id=\"text-box-2011658127\" class=\"text-box banner-layer x100 md-x100 lg-x100 y50 md-y50 lg-y50 res-text\">\n                                <div class=\"text-box-content text box-shadow-3 dark\">\n              \n              <div class=\"text-inner text-center\">\n                  \n<h2 class=\"uppercase\"><strong>visitas guiadas<br \/><\/strong><\/h2>\n<h3>Visita Guiadas<\/h3>\n<p>Descubre el arte de los vinos volc\u00e1nicos en un entorno \u00fanico. \u00a1Sum\u00e9rgete en nuestros vi\u00f1edos y vive una experiencia inolvidable!<\/p>\n<a href=\"https:\/\/dev.lageria.com\/fr\/visitas-guiadas\/\" class=\"button primary\" >\n\t\t<span>contratar<\/span>\n\t<\/a>\n\n<a href=\"https:\/\/dev.lageria.com\/calendario\/\" class=\"button alert\" >\n\t\t<span>horarios<\/span>\n\t<\/a>\n\n              <\/div>\n           <\/div>\n                            \n<style>\n#text-box-2011658127 .text-box-content {\n  background-color: rgba(0, 0, 0, 0.779);\n  font-size: 100%;\n}\n#text-box-2011658127 .text-inner {\n  padding: 30px 30px 30px 30px;\n}\n#text-box-2011658127 {\n  width: 60%;\n}\n@media (min-width:550px) {\n  #text-box-2011658127 {\n    width: 54%;\n  }\n}\n<\/style>\n    <\/div>\n \n        <\/div>\n      <\/div>\n\n            \n<style>\n#banner-1784447019 {\n  padding-top: 700px;\n}\n#banner-1784447019 .overlay {\n  background-color: rgba(0, 0, 0, 0.2);\n}\n<\/style>\n  <\/div>\n\n\n\n  <div class=\"banner has-hover has-video\" id=\"banner-1769129096\">\n          <div class=\"banner-inner fill\">\n        <div class=\"banner-bg fill\" >\n            <img loading=\"lazy\" decoding=\"async\" width=\"1920\" height=\"1280\" src=\"https:\/\/dev.lageria.com\/wp-content\/uploads\/2025\/10\/IMG_0115-1.jpg\" class=\"bg attachment-original size-original\" alt=\"\" \/>            \t<div class=\"video-overlay no-click fill hide-for-medium\"><\/div>\n\t<video class=\"video-bg fill hide-for-medium\" preload playsinline autoplay muted loop>\n\t\t<source src=\"https:\/\/dev.lageria.com\/LageriaLifeSt.mp4\" type=\"video\/mp4\">\t<\/video>\n            <div class=\"overlay\"><\/div>            \n                    <\/div>\n\t\t\n        <div class=\"banner-layers container\">\n            <div class=\"fill banner-link\"><\/div>            \n   <div id=\"text-box-269179153\" class=\"text-box banner-layer x50 md-x50 lg-x50 y50 md-y50 lg-y50 res-text\">\n                                <div class=\"text-box-content text dark\">\n              \n              <div class=\"text-inner text-center\">\n                  \n              <\/div>\n           <\/div>\n                            \n<style>\n#text-box-269179153 {\n  width: 60%;\n}\n#text-box-269179153 .text-box-content {\n  font-size: 100%;\n}\n@media (min-width:550px) {\n  #text-box-269179153 {\n    width: 60%;\n  }\n}\n<\/style>\n    <\/div>\n \n        <\/div>\n      <\/div>\n\n            \n<style>\n#banner-1769129096 {\n  padding-top: 700px;\n}\n#banner-1769129096 .overlay {\n  background-color: rgba(0, 0, 0, 0.2);\n}\n<\/style>\n  <\/div>\n\n\n     <\/div>\n\n     <div class=\"loading-spin dark large centered\"><\/div>\n\n\t<\/div>\n\n\n<div class=\"row\"  id=\"row-1220276500\">\n\n\t<div id=\"col-1840230121\" class=\"col medium-4 small-12 large-4\"  >\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n\n  <div class=\"banner has-hover bg-zoom-fade\" id=\"banner-235552221\">\n          <div class=\"banner-inner fill\">\n        <div class=\"banner-bg fill\" >\n            <img loading=\"lazy\" decoding=\"async\" width=\"809\" height=\"1024\" src=\"https:\/\/dev.lageria.com\/wp-content\/uploads\/2021\/04\/20201228_085747-1-809x1024.jpg\" class=\"bg attachment-large size-large\" alt=\"\" \/>                                    \n                    <\/div>\n\t\t\n        <div class=\"banner-layers container\">\n            <a class=\"fill\" href=\"http:\/\/blog\"><div class=\"fill banner-link\"><\/div><\/a>            \n   <div id=\"text-box-1362017855\" class=\"text-box banner-layer x50 md-x50 lg-x50 y50 md-y50 lg-y50 res-text\">\n                                <div class=\"text-box-content text dark\">\n              \n              <div class=\"text-inner text-center\">\n                  \n<h2><strong><span class=\"uppercase\">VISITAS GUIADAS<br \/><\/span><\/strong><\/h2>\n<div class=\"is-divider divider clearfix\" ><\/div>\n              <\/div>\n           <\/div>\n                            \n<style>\n#text-box-1362017855 {\n  width: 60%;\n}\n#text-box-1362017855 .text-box-content {\n  font-size: 100%;\n}\n<\/style>\n    <\/div>\n \n        <\/div>\n      <\/div>\n\n            \n<style>\n#banner-235552221 {\n  padding-top: 160px;\n}\n#banner-235552221 .banner-bg img {\n  object-position: 52% 82%;\n}\n<\/style>\n  <\/div>\n\n\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\n\n\t<div id=\"col-1575396793\" class=\"col medium-4 small-12 large-4\"  >\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n\n  <div class=\"banner has-hover bg-zoom-fade\" id=\"banner-2078647052\">\n          <div class=\"banner-inner fill\">\n        <div class=\"banner-bg fill\" >\n            <img loading=\"lazy\" decoding=\"async\" width=\"1020\" height=\"680\" src=\"https:\/\/dev.lageria.com\/wp-content\/uploads\/2015\/07\/IMG_0115-1024x683.jpg\" class=\"bg attachment-large size-large\" alt=\"\" \/>                                    \n                    <\/div>\n\t\t\n        <div class=\"banner-layers container\">\n            <div class=\"fill banner-link\"><\/div>            \n   <div id=\"text-box-1044270294\" class=\"text-box banner-layer x50 md-x50 lg-x50 y50 md-y50 lg-y50 res-text\">\n                                <div class=\"text-box-content text dark\">\n              \n              <div class=\"text-inner text-center\">\n                  \n<h2><strong><span class=\"uppercase\">SELECCI\u00d3N GOURMET<br \/><\/span><\/strong><\/h2>\n<div class=\"is-divider divider clearfix\" ><\/div>\n              <\/div>\n           <\/div>\n                            \n<style>\n#text-box-1044270294 {\n  width: 60%;\n}\n#text-box-1044270294 .text-box-content {\n  font-size: 100%;\n}\n<\/style>\n    <\/div>\n \n        <\/div>\n      <\/div>\n\n            \n<style>\n#banner-2078647052 {\n  padding-top: 160px;\n}\n<\/style>\n  <\/div>\n\n\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\n\n\t<div id=\"col-252892728\" class=\"col medium-4 small-12 large-4\"  >\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n\n  <div class=\"banner has-hover bg-zoom-fade\" id=\"banner-2146736102\">\n          <div class=\"banner-inner fill\">\n        <div class=\"banner-bg fill\" >\n            <img loading=\"lazy\" decoding=\"async\" width=\"1020\" height=\"680\" src=\"https:\/\/dev.lageria.com\/wp-content\/uploads\/2025\/10\/lanzarote-canary-island-1200x800-1-1024x683.jpg\" class=\"bg attachment-large size-large\" alt=\"\" \/>                                    \n                    <\/div>\n\t\t\n        <div class=\"banner-layers container\">\n            <a class=\"fill\" href=\"http:\/\/about-us\"><div class=\"fill banner-link\"><\/div><\/a>            \n   <div id=\"text-box-1024036288\" class=\"text-box banner-layer x50 md-x50 lg-x50 y50 md-y50 lg-y50 res-text\">\n                                <div class=\"text-box-content text dark\">\n              \n              <div class=\"text-inner text-center\">\n                  \n<h2><strong><span class=\"uppercase\">DENOMINACION DE ORIGEN<br \/><\/span><\/strong><\/h2>\n<div class=\"is-divider divider clearfix\" ><\/div>\n              <\/div>\n           <\/div>\n                            \n<style>\n#text-box-1024036288 {\n  width: 60%;\n}\n#text-box-1024036288 .text-box-content {\n  font-size: 100%;\n}\n<\/style>\n    <\/div>\n \n        <\/div>\n      <\/div>\n\n            \n<style>\n#banner-2146736102 {\n  padding-top: 160px;\n}\n#banner-2146736102 .banner-bg img {\n  object-position: 71% 0%;\n}\n<\/style>\n  <\/div>\n\n\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\n<\/div>\n<div class=\"container section-title-container\" ><h3 class=\"section-title section-title-center\"><b aria-hidden=\"true\"><\/b><span class=\"section-title-main\" >esta es nuestra seleccion la geria<\/span><b aria-hidden=\"true\"><\/b><\/h3><\/div>\n\t\n  \n    <div class=\"row  equalize-box large-columns-4 medium-columns-3 small-columns-2 row-small slider row-slider slider-nav-reveal slider-nav-push\"  data-flickity-options='{&quot;imagesLoaded&quot;: true, &quot;groupCells&quot;: &quot;100%&quot;, &quot;dragThreshold&quot; : 5, &quot;cellAlign&quot;: &quot;left&quot;,&quot;wrapAround&quot;: true,&quot;prevNextButtons&quot;: true,&quot;percentPosition&quot;: true,&quot;pageDots&quot;: true, &quot;rightToLeft&quot;: false, &quot;autoPlay&quot; : 5000}' >\n\n  <\/div>\n<div class=\"row row-collapse row-full-width align-equal\"  id=\"row-755405703\">\n\n\t<div id=\"col-1220564881\" class=\"col medium-7 small-12 large-7\"  >\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n\n\t<section class=\"section dark\" id=\"section_730686204\">\n\t\t<div class=\"section-bg fill\" >\n\t\t\t\t\t\t\t\t\t\n\t\t\t\n\n\t\t<\/div>\n\n\t\t\n\n\t\t<div class=\"section-content relative\">\n\t\t\t\n<div class=\"row\"  id=\"row-560883417\">\n\n\t<div id=\"col-1213539353\" class=\"col medium-12 small-12 large-11\"  >\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n\t<div id=\"gap-1126071648\" class=\"gap-element clearfix\" style=\"display:block; height:auto;\">\n\t\t\n<style>\n#gap-1126071648 {\n  padding-top: 30px;\n}\n<\/style>\n\t<\/div>\n\t\n\t<div id=\"text-1192677815\" class=\"text\">\n\t\t\n<h3 class=\"uppercase\">\u00ab La Geria : tradition, volcan et passion dans un verre \u00bb<\/h3>\n\t\t\n<style>\n#text-1192677815 {\n  font-size: 1.25rem;\n  line-height: 1.25;\n  text-align: center;\n}\n<\/style>\n\t<\/div>\n\t\n<div class=\"is-divider divider clearfix\" style=\"margin-top:1.6em;margin-bottom:1.6em;max-width:150px;background-color:rgb(255, 255, 255);\"><\/div>\n\t<div id=\"text-212668958\" class=\"text\">\n\t\t\n<p><main class=\"main-content svelte-29epsp\"><\/p>\n<div class=\"main-content svelte-mhuesr\">\n<div class=\"translator-container svelte-bad754\" data-testid=\"side-panel-translator\">\n<div class=\"output-area svelte-10aez33\" dir=\"ltr\" data-testid=\"side-panel-output\">visite guid\u00e9e<\/div>\n<\/div>\n<\/div>\n<p><\/main><br \/>\n\t\t\n<style>\n#text-212668958 {\n  font-size: 4rem;\n  line-height: 0.75;\n}\n<\/style>\n\t<\/div>\n\t\n<p>\u00a0<\/p>\n<div class=\"main-content svelte-mhuesr\">\n<div class=\"translator-container svelte-bad754\" data-testid=\"side-panel-translator\">\n<div class=\"output-area svelte-10aez33\" dir=\"ltr\" data-testid=\"side-panel-output\">\u00c0 La Geria, vous pourrez participer \u00e0 des **d\u00e9gustations de vin** et des **visites guid\u00e9es** qui vous plongeront dans la tradition viticole de l&#8217;\u00eele. Les visites vous permettent de d\u00e9couvrir de pr\u00e8s les vignobles singuliers plant\u00e9s sur un sol volcanique, de d\u00e9couvrir le processus de production du c\u00e9l\u00e8bre vin Malvas\u00eda et de d\u00e9guster certaines des meilleures vari\u00e9t\u00e9s de la r\u00e9gion, tout en \u00e9tant entour\u00e9 d&#8217;un paysage spectaculaire et unique.<\/div>\n<\/div>\n<\/div>\n<p>\u00a0<\/p>\n\t<div id=\"stack-770971626\" class=\"stack stack-row justify-start items-stretch sm:stack-col\">\n\t\t\n<a href=\"https:\/\/dev.lageria.com\/fr\/visitas-guiadas\/\" class=\"button success\" style=\"padding:8px 20px 8px 20px;\">\n\t\t<span>voir les dates<\/span>\n\t<\/a>\n\n\t\t\n<style>\n#stack-770971626 > * {\n  --stack-gap: 0.5rem;\n}\n<\/style>\n\t<\/div>\n\t\n\t\t<\/div>\n\t\t\t\t\n<style>\n#col-1213539353 > .col-inner {\n  padding: 0px 0px 0px 0;\n}\n@media (min-width:850px) {\n  #col-1213539353 > .col-inner {\n    padding: 0px 0px 0px 20%;\n  }\n}\n<\/style>\n\t<\/div>\n\n\t\n<\/div>\n\t\t<\/div>\n\n\t\t\n<style>\n#section_730686204 {\n  padding-top: 30px;\n  padding-bottom: 30px;\n  min-height: 300px;\n  background-color: rgb(164, 184, 26);\n}\n@media (min-width:550px) {\n  #section_730686204 {\n    min-height: 400px;\n  }\n}\n@media (min-width:850px) {\n  #section_730686204 {\n    min-height: 500px;\n  }\n}\n<\/style>\n\t<\/section>\n\t\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\n\n\t<div id=\"col-1359990918\" class=\"col medium-5 small-12 large-5 small-col-first\"  >\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n\n  <div class=\"banner has-hover\" id=\"banner-972482595\">\n          <div class=\"banner-inner fill\">\n        <div class=\"banner-bg fill\" >\n            <img loading=\"lazy\" decoding=\"async\" width=\"1020\" height=\"680\" src=\"https:\/\/dev.lageria.com\/wp-content\/uploads\/2025\/10\/IMG_0115-1-1024x683.jpg\" class=\"bg attachment-large size-large\" alt=\"\" \/>                                    \n                    <\/div>\n\t\t\n        <div class=\"banner-layers container\">\n            <div class=\"fill banner-link\"><\/div>            \n   <div id=\"text-box-505308078\" class=\"text-box banner-layer x50 md-x50 lg-x50 y50 md-y50 lg-y50 res-text\">\n                                <div class=\"text-box-content text dark\">\n              \n              <div class=\"text-inner text-center\">\n                  \n              <\/div>\n           <\/div>\n                            \n<style>\n#text-box-505308078 {\n  width: 60%;\n}\n#text-box-505308078 .text-box-content {\n  font-size: 100%;\n}\n<\/style>\n    <\/div>\n \n        <\/div>\n      <\/div>\n\n            \n<style>\n#banner-972482595 {\n  padding-top: 250px;\n  background-color: rgba(255, 255, 255, 0);\n}\n#banner-972482595 .banner-bg img {\n  object-position: 60% 66%;\n}\n@media (min-width:550px) {\n  #banner-972482595 {\n    padding-top: 400px;\n  }\n}\n@media (min-width:850px) {\n  #banner-972482595 {\n    padding-top: 500px;\n  }\n}\n<\/style>\n  <\/div>\n\n\n\n<div class=\"latepoint-book-form-wrapper os-loading os_init_booking_form\" id=\"latepointBookForm_6a575b643f864\" data-selected-location=\"1\" data-selected-agent=\"3\" data-hide-side-panel=\"yes\" data-hide-summary=\"yes\" >\n\t\t\t\t\t\t<div class=\"latepoint-w latepoint-inline-form latepoint-hide-side-panel\">\n\t\t\t\t\t\t\t<div class=\"latepoint-booking-form-element\">\n\t\t\t\t\t\t\t\t<div class=\"latepoint-side-panel\"><\/div>\n\t\t\t\t\t\t\t\t<div class=\"latepoint-form-w\"><\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\n<\/div>\n<div class=\"container section-title-container\" ><h3 class=\"section-title section-title-center\"><b aria-hidden=\"true\"><\/b><span class=\"section-title-main\" style=\"font-size:undefined%;\">produits les plus vendus<\/span><b aria-hidden=\"true\"><\/b><\/h3><\/div>\n\t\n  \n    <div class=\"row  equalize-box large-columns-4 medium-columns-3 small-columns-2 row-small slider row-slider slider-nav-reveal slider-nav-push\"  data-flickity-options='{&quot;imagesLoaded&quot;: true, &quot;groupCells&quot;: &quot;100%&quot;, &quot;dragThreshold&quot; : 5, &quot;cellAlign&quot;: &quot;left&quot;,&quot;wrapAround&quot;: true,&quot;prevNextButtons&quot;: true,&quot;percentPosition&quot;: true,&quot;pageDots&quot;: false, &quot;rightToLeft&quot;: false, &quot;autoPlay&quot; : 6000}' >\n\n  <\/div>\n<div class=\"container section-title-container hidden\" ><h3 class=\"section-title section-title-center\"><b aria-hidden=\"true\"><\/b><span class=\"section-title-main\" >nos cat\u00e9gories<\/span><b aria-hidden=\"true\"><\/b><\/h3><\/div>\n\n  \n    <div class=\"row large-columns-4 medium-columns-3 small-columns-2 row-small slider row-slider slider-nav-reveal\"  data-flickity-options='{&quot;imagesLoaded&quot;: true, &quot;groupCells&quot;: &quot;100%&quot;, &quot;dragThreshold&quot; : 5, &quot;cellAlign&quot;: &quot;left&quot;,&quot;wrapAround&quot;: true,&quot;prevNextButtons&quot;: true,&quot;percentPosition&quot;: true,&quot;pageDots&quot;: false, &quot;rightToLeft&quot;: false, &quot;autoPlay&quot; : false}' >\n\n  <\/div>\n<div class=\"slider-wrapper relative\" id=\"slider-232688547\" >\n    <div class=\"slider slider-nav-circle slider-nav-large slider-nav-light slider-style-normal\"\n        data-flickity-options='{\n            \"cellAlign\": \"center\",\n            \"imagesLoaded\": true,\n            \"lazyLoad\": 1,\n            \"freeScroll\": false,\n            \"wrapAround\": true,\n            \"autoPlay\": 2000,\n            \"pauseAutoPlayOnHover\" : true,\n            \"prevNextButtons\": true,\n            \"contain\" : true,\n            \"adaptiveHeight\" : true,\n            \"dragThreshold\" : 10,\n            \"percentPosition\": true,\n            \"pageDots\": true,\n            \"rightToLeft\": false,\n            \"draggable\": true,\n            \"selectedAttraction\": 0.1,\n            \"parallax\" : 0,\n            \"friction\": 0.6        }'\n        >\n        \n\n\t<section class=\"section dark\" id=\"section_1576874192\">\n\t\t<div class=\"section-bg fill\" >\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1620\" height=\"1080\" src=\"https:\/\/dev.lageria.com\/wp-content\/uploads\/2025\/10\/volcanic-landscape-with-black-sand-vineyards.jpg\" class=\"bg attachment- size-\" alt=\"\" \/>\t\t\t\t\t\t<div class=\"section-bg-overlay absolute fill\"><\/div>\n\t\t\t\n\n\t\t<\/div>\n\n\t\t\n\n\t\t<div class=\"section-content relative\">\n\t\t\t\n\t<div id=\"gap-1206849961\" class=\"gap-element clearfix\" style=\"display:block; height:auto;\">\n\t\t\n<style>\n#gap-1206849961 {\n  padding-top: 50px;\n}\n<\/style>\n\t<\/div>\n\t\n<div class=\"row align-center\"  id=\"row-1233242550\">\n\n\t<div id=\"col-429654734\" class=\"col medium-9 small-12 large-7\"  >\n\t\t\t\t<div class=\"col-inner text-center\"  >\n\t\t\t\n\t\t\t\n<h6>Conoce un poco m\u00e1s nuestras vi\u00f1as y actividades<\/h6>\n\t<div id=\"text-1460882571\" class=\"text\">\n\t\t\n<h2>Video de La Geria<\/h2>\n\t\t\n<style>\n#text-1460882571 {\n  font-size: 2rem;\n}\n<\/style>\n\t<\/div>\n\t\n<div class=\"video-button-wrapper\"><a href=\"https:\/\/www.youtube.com\/watch?v=gNWJzwvSk8I\" class=\"button open-video icon circle is-outline is-xlarge\" role=\"button\" aria-label=\"Open video in lightbox\" data-flatsome-role-button><i class=\"icon-play\" aria-hidden=\"true\" style=\"font-size:1.5em;\"><\/i><\/a><\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\n<\/div>\n\t\t<\/div>\n\n\t\t\n<style>\n#section_1576874192 {\n  padding-top: 30px;\n  padding-bottom: 30px;\n  min-height: 400px;\n}\n#section_1576874192 .section-bg-overlay {\n  background-color: rgba(0, 0, 0, 0.3);\n}\n#section_1576874192 .section-bg img {\n  object-position: 64% 37%;\n}\n@media (min-width:550px) {\n  #section_1576874192 {\n    min-height: 500px;\n  }\n}\n<\/style>\n\t<\/section>\n\t\n\n  <div class=\"banner has-hover has-parallax\" id=\"banner-591982349\">\n          <div class=\"banner-inner fill\">\n        <div class=\"banner-bg fill\" data-parallax=\"-1\" data-parallax-container=\".banner\" data-parallax-background>\n            <img loading=\"lazy\" decoding=\"async\" width=\"1920\" height=\"1076\" src=\"https:\/\/dev.lageria.com\/wp-content\/uploads\/2025\/10\/stunning-sunset-view-la-geria-lanzarote-island.jpg\" class=\"bg attachment-original size-original\" alt=\"\" \/>                        <div class=\"overlay\"><\/div>            \n                    <\/div>\n\t\t\n        <div class=\"banner-layers container\">\n            <div class=\"fill banner-link\"><\/div>            \n   <div id=\"text-box-1955279426\" class=\"text-box banner-layer x50 md-x50 lg-x50 y50 md-y50 lg-y50 res-text\">\n                                <div class=\"text-box-content text dark\">\n              \n              <div class=\"text-inner text-center\">\n                  \n  <div class=\"icon-box testimonial-box icon-box-left text-left\">\n                <div class=\"icon-box-text p-last-0\">\n          <div class=\"star-rating\" role=\"img\" aria-label=\"Rated 5 out of 5\"><span style=\"width:100%\"><strong class=\"rating\"><\/strong><\/span><\/div>  \t\t\t\t<div class=\"testimonial-text line-height-small italic test_text first-reset last-reset is-italic\">\n            \n<p><main class=\"main-content svelte-29epsp\"><\/p>\n<div class=\"main-content svelte-mhuesr\">\n<div class=\"translator-container svelte-bad754\" data-testid=\"side-panel-translator\">\n<div class=\"output-area svelte-10aez33\" dir=\"ltr\" data-testid=\"side-panel-output\">La Geria est un lieu o\u00f9 l&#8217;ing\u00e9niosit\u00e9 humaine et la nature volcanique s&#8217;unissent pour cr\u00e9er des vins uniques. \ud83c\udf47\ud83c\udf0b Ses paysages de vignobles sont impressionnants, et chaque verre de vin refl\u00e8te la saveur authentique de Lanzarote, avec des notes fra\u00eeches et min\u00e9rales. Visiter La Geria, c&#8217;est vivre la tradition et la passion volcanique \u00e0 chaque gorg\u00e9e. \ud83e\udd42\u2728 #LaGeria #VinsDeLanzarote #SaveurVolcanique<\/div>\n<\/div>\n<\/div>\n<p><\/main><\/p>\n          <\/div>\n          <div class=\"testimonial-meta pt-half\">\n             <strong class=\"testimonial-name test_name\">Lucy Anderson<\/strong>\n             <span class=\"testimonial-name-divider\"> \/ <\/span>             <span class=\"testimonial-company test_company\">Facebook<\/span>\n          <\/div>\n        <\/div>\n  <\/div>\n\n  \n              <\/div>\n           <\/div>\n                            \n<style>\n#text-box-1955279426 {\n  width: 78%;\n}\n#text-box-1955279426 .text-box-content {\n  font-size: 100%;\n}\n<\/style>\n    <\/div>\n \n        <\/div>\n      <\/div>\n\n            \n<style>\n#banner-591982349 {\n  padding-top: 300px;\n  background-color: rgb(255,255,255);\n}\n#banner-591982349 .overlay {\n  background-color: rgba(0,0,0,.5);\n}\n#banner-591982349 .banner-bg img {\n  object-position: 44% 30%;\n}\n<\/style>\n  <\/div>\n\n\n     <\/div>\n\n     <div class=\"loading-spin dark large centered\"><\/div>\n\n\t<\/div>\n\n\n<div class=\"container section-title-container\" ><h3 class=\"section-title section-title-center\"><b aria-hidden=\"true\"><\/b><span class=\"section-title-main\" style=\"font-size:undefined%;\">\u00faltimas noticias<\/span><b aria-hidden=\"true\"><\/b><\/h3><\/div>\n<div class=\"row row-collapse row-full-width\"  id=\"row-2077958469\">\n\n\t<div id=\"col-724019443\" class=\"col medium-4 small-6 large-4\"  >\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n\n\t<section class=\"section dark\" id=\"section_1108905803\">\n\t\t<div class=\"section-bg fill\" >\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1080\" height=\"1434\" src=\"https:\/\/dev.lageria.com\/wp-content\/uploads\/2025\/10\/glass-wine-with-stunning-view-vineyard-sunset.jpg\" class=\"bg attachment- size-\" alt=\"\" \/>\t\t\t\t\t\t<div class=\"section-bg-overlay absolute fill\"><\/div>\n\t\t\t\n\n\t\t<\/div>\n\n\t\t\n\n\t\t<div class=\"section-content relative\">\n\t\t\t\n\n\t\t<div class=\"icon-box featured-box icon-box-center text-center\"  >\n\t\t\t\t\t<div class=\"icon-box-img\" style=\"width: 60px\">\n\t\t\t\t<div class=\"icon\">\n\t\t\t\t\t<div class=\"icon-inner\" >\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t\t\t<div class=\"icon-box-text last-reset\">\n\t\t\t\t\t\t\t\t\t\n<h3>Catas en Espa\u00f1ol<\/h3>\n\t\t<\/div>\n\t<\/div>\n\t\n\t\n\t\t<\/div>\n\n\t\t\n<style>\n#section_1108905803 {\n  padding-top: 30px;\n  padding-bottom: 30px;\n  min-height: 300px;\n}\n#section_1108905803 .section-bg-overlay {\n  background-color: rgba(0, 0, 0, 0.4);\n}\n#section_1108905803 .section-bg img {\n  object-position: 0% 100%;\n}\n<\/style>\n\t<\/section>\n\t\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\n\n\t<div id=\"col-1222052667\" class=\"col medium-4 small-6 large-4\"  >\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n\n\t<section class=\"section dark\" id=\"section_527979075\">\n\t\t<div class=\"section-bg fill\" >\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1620\" height=\"1080\" src=\"https:\/\/dev.lageria.com\/wp-content\/uploads\/2025\/10\/volcanic-landscape-with-black-sand-vineyards.jpg\" class=\"bg attachment- size-\" alt=\"\" \/>\t\t\t\t\t\t<div class=\"section-bg-overlay absolute fill\"><\/div>\n\t\t\t\n\n\t\t<\/div>\n\n\t\t\n\n\t\t<div class=\"section-content relative\">\n\t\t\t\n\n\t\t<div class=\"icon-box featured-box icon-box-center text-center\"  >\n\t\t\t\t\t<div class=\"icon-box-img\" style=\"width: 60px\">\n\t\t\t\t<div class=\"icon\">\n\t\t\t\t\t<div class=\"icon-inner\" >\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t\t\t<div class=\"icon-box-text last-reset\">\n\t\t\t\t\t\t\t\t\t\n<h3>Catas en Ingl\u00e9s<\/h3>\n\t\t<\/div>\n\t<\/div>\n\t\n\t\n\t\t<\/div>\n\n\t\t\n<style>\n#section_527979075 {\n  padding-top: 30px;\n  padding-bottom: 30px;\n  min-height: 300px;\n}\n#section_527979075 .section-bg-overlay {\n  background-color: rgba(0, 0, 0, 0.26);\n}\n<\/style>\n\t<\/section>\n\t\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\n\n\t<div id=\"col-409112855\" class=\"col medium-4 small-6 large-4\"  >\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n\n\t<section class=\"section dark\" id=\"section_1471110199\">\n\t\t<div class=\"section-bg fill\" >\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1200\" height=\"800\" src=\"https:\/\/dev.lageria.com\/wp-content\/uploads\/2025\/10\/lanzarote-canary-island-1200x800-1.jpg\" class=\"bg attachment- size-\" alt=\"\" \/>\t\t\t\t\t\t<div class=\"section-bg-overlay absolute fill\"><\/div>\n\t\t\t\n\n\t\t<\/div>\n\n\t\t\n\n\t\t<div class=\"section-content relative\">\n\t\t\t\n\n\t\t<div class=\"icon-box featured-box icon-box-center text-center\"  >\n\t\t\t\t\t<div class=\"icon-box-img\" style=\"width: 60px\">\n\t\t\t\t<div class=\"icon\">\n\t\t\t\t\t<div class=\"icon-inner\" >\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t\t\t<div class=\"icon-box-text last-reset\">\n\t\t\t\t\t\t\t\t\t\n<h3>Catas en Franc\u00e9s<\/h3>\n\t\t<\/div>\n\t<\/div>\n\t\n\t\n\t\t<\/div>\n\n\t\t\n<style>\n#section_1471110199 {\n  padding-top: 30px;\n  padding-bottom: 30px;\n  min-height: 300px;\n}\n#section_1471110199 .section-bg-overlay {\n  background-color: rgba(0, 0, 0, 0.26);\n}\n<\/style>\n\t<\/section>\n\t\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\n<\/div>\n\n  \n    <div class=\"row large-columns-4 medium-columns-3 small-columns-1 slider row-slider slider-nav-reveal slider-nav-push\"  data-flickity-options='{&quot;imagesLoaded&quot;: true, &quot;groupCells&quot;: &quot;100%&quot;, &quot;dragThreshold&quot; : 5, &quot;cellAlign&quot;: &quot;left&quot;,&quot;wrapAround&quot;: true,&quot;prevNextButtons&quot;: true,&quot;percentPosition&quot;: true,&quot;pageDots&quot;: false, &quot;rightToLeft&quot;: false, &quot;autoPlay&quot; : false}' >\n\n  <\/div>\n<div class=\"row\"  id=\"row-939496584\">\n\n\t<div id=\"col-2106882904\" class=\"col small-12 large-12\"  >\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n\t<div id=\"text-1365388109\" class=\"text\">\n\t\t\n<p>Esta empresa ha recibido una subvenci\u00f3n para la Instalaci\u00f3n de Planta para Generaci\u00f3n El\u00e9ctrica Fotovoltaica proveniente del Fomento de la Descarbonizaci\u00f3n del Sector Industrial en la Estrategia de Energ\u00eda Sostenible en Canarias del Plan de Recuperaci\u00f3n, Transformaci\u00f3n y Resiliencia. Consejer\u00eda de Transici\u00f3n Ecol\u00f3gica del Gobierno de Canarias. Financiado por la Uni\u00f3n Europea \u2013NextGenerationEU<\/p>\n\t\t\n<style>\n#text-1365388109 {\n  color: rgb(0,0,0);\n}\n#text-1365388109 > * {\n  color: rgb(0,0,0);\n}\n<\/style>\n\t<\/div>\n\t\n\t<div class=\"img has-hover x md-x lg-x y md-y lg-y\" id=\"image_898498462\">\n\t\t\t\t\t\t\t\t<div class=\"img-inner dark\" >\n\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\n<style>\n#image_898498462 {\n  width: 100%;\n}\n<\/style>\n\t<\/div>\n\t\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\n<\/div>\n","protected":false},"excerpt":{"rendered":"","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":1,"comment_status":"closed","ping_status":"closed","template":"page-blank.php","meta":{"footnotes":""},"class_list":["post-235914","page","type-page","status-publish","hentry"],"_links":{"self":[{"href":"https:\/\/dev.lageria.com\/fr\/wp-json\/wp\/v2\/pages\/235914","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dev.lageria.com\/fr\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/dev.lageria.com\/fr\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/dev.lageria.com\/fr\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/dev.lageria.com\/fr\/wp-json\/wp\/v2\/comments?post=235914"}],"version-history":[{"count":5,"href":"https:\/\/dev.lageria.com\/fr\/wp-json\/wp\/v2\/pages\/235914\/revisions"}],"predecessor-version":[{"id":250775,"href":"https:\/\/dev.lageria.com\/fr\/wp-json\/wp\/v2\/pages\/235914\/revisions\/250775"}],"wp:attachment":[{"href":"https:\/\/dev.lageria.com\/fr\/wp-json\/wp\/v2\/media?parent=235914"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}